{"id":5742,"date":"2023-07-31T17:13:24","date_gmt":"2023-07-31T09:13:24","guid":{"rendered":"https:\/\/ecofiberpultrusion.com\/products\/piquets-en-fibre-de-verre-recouverts-dun-voile-polyester-anti-uv\/"},"modified":"2023-09-14T14:18:59","modified_gmt":"2023-09-14T06:18:59","slug":"piquets-en-fibre-de-verre-avec-voile-uv","status":"publish","type":"page","link":"https:\/\/ecofiberpultrusion.com\/fr\/products\/piquets-en-fibre-de-verre-avec-voile-uv\/","title":{"rendered":"Piquets en fibre de verre avec voile UV"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5742\" class=\"elementor elementor-5742 elementor-1854\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f57d69 elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"6f57d69\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47228c7\" data-id=\"47228c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-745baeb elementor-widget elementor-widget-heading\" data-id=\"745baeb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">DES PRODUITS<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-319e374 e-con-full e-flex e-con e-parent\" data-id=\"319e374\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78995a6 elementor-widget elementor-widget-heading\" data-id=\"78995a6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\"><br>Piquets en fibre de verre recouverts d'un voile polyester anti-UV<br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fc367a1 e-grid e-con-boxed e-con e-parent\" data-id=\"fc367a1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b8e8c3 elementor-widget elementor-widget-image\" data-id=\"2b8e8c3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/elementor\/thumbs\/details-fiberglass-stakes-with-UV-veil-qaqgyv6j04m6gyson4fra5i98skc42mlno7e8n0beg.jpg\" title=\"details-fiberglass-stakes-with-UV-veil\" alt=\"details-fiberglass-stakes-with-UV-veil\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b59250 elementor-widget elementor-widget-text-editor\" data-id=\"0b59250\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<\/p>\n<p>Piquets en fibre de verre recouverts d&#8217;un voile polyester anti-UV Le voile de polyester peut prot\u00e9ger la fibre et la r\u00e9sine \u00e0 l&#8217;int\u00e9rieur des piquets des rayons ultraviolets directs, de sorte que le produit a une dur\u00e9e de vie plus longue. Le voile fournit \u00e9galement une barri\u00e8re physique qui emp\u00eache tout \u00e9clat de verre bris\u00e9 de remonter \u00e0 la surface. Gr\u00e2ce \u00e0 son excellente r\u00e9sistance aux UV et \u00e0 sa longue dur\u00e9e de vie, ce produit devient de plus en plus populaire. <\/p>\n<p>Le mat\u00e9riau en fibre de verre ne pourrira pas, ne rouillera pas, ne se corrodera pas et ne se d\u00e9composera pas et s&#8217;amortit en quelques ann\u00e9es. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d0bdf87 e-grid e-con-boxed e-con e-parent\" data-id=\"d0bdf87\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1493b2 elementor-widget elementor-widget-text-editor\" data-id=\"a1493b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"x-el x-el-h4 c1-1 c1-2 c1-1q c1-1e c1-a5 c1-18 c1-16 c1-15 c1-17 c1-b c1-30 c1-5v c1-44 c1-5x c1-5z c1-60 c1-61\" role=\"heading\" aria-level=\"4\" data-ux=\"ContentHeading\" data-aid=\"CONTENT_HEADLINE1_RENDERED\" data-typography=\"HeadingDelta\">Caract\u00e9ristiques<\/h4>\n<\/p>\n<div class=\"x-el c1-1 c1-2 c1-1q c1-1e c1-4u c1-15 c1-17 c1-8u c1-8v c1-8w c1-8x c1-8y c1-8z c1-90 c1-91 c1-92 c1-93 c1-94 c1-95 c1-96 c1-97 c1-98 c1-99 c1-9a c1-9b c1-9c c1-9d c1-9e c1-9f c1-9g c1-9h c1-9i c1-9j c1-9k c1-9l c1-7b c1-b c1-3o c1-c c1-44 c1-d c1-e c1-f c1-g x-rt\" data-ux=\"ContentText\" data-aid=\"CONTENT_DESCRIPTION1_RENDERED\" data-typography=\"BodyAlpha\">\n<ul>\n<li><em class=\"x-el x-el-span c1-1n c1-1o c1-b c1-9n c1-32 c1-20 c1-9p c1-9q\">Le piquet est recouvert d&#8217;un voile de polyester UV sur sa surface, ce qui prolonge la dur\u00e9e de vie du piquet et fournit une barri\u00e8re physique qui emp\u00eache tout \u00e9clat de verre bris\u00e9 de remonter \u00e0 la surface.<\/em><\/li>\n<li><em class=\"x-el x-el-span c1-1n c1-1o c1-b c1-9n c1-32 c1-20 c1-9p c1-9q\">Le piquet en fibre de verre est solide, r\u00e9sistant, ne rouille pas, ne se d\u00e9colore pas facilement.<\/em><\/li>\n<li><em class=\"x-el x-el-span c1-1n c1-1o c1-b c1-9n c1-32 c1-20 c1-9p c1-9q\">Longue dur\u00e9e de vie, peut \u00eatre utilis\u00e9 \u00e0 plusieurs reprises pendant de nombreuses ann\u00e9es, vous permettant d&#8217;\u00e9conomiser beaucoup d&#8217;argent. <\/em><\/li>\n<li><em class=\"x-el x-el-span c1-1n c1-1o c1-b c1-9n c1-32 c1-20 c1-9p c1-9q\">Installation facile. L&#8217;extr\u00e9mit\u00e9 inf\u00e9rieure du piquet est pointue, ce qui vous permet d&#8217;ins\u00e9rer facilement le piquet dans le sol.<\/em><\/li>\n<li><em class=\"x-el x-el-span c1-1n c1-1o c1-b c1-9n c1-32 c1-20 c1-9p c1-9q\">Diff\u00e9rentes tailles et couleurs sont disponibles<\/em><\/li>\n<li><em class=\"x-el x-el-span c1-1n c1-1o c1-b c1-9n c1-32 c1-20 c1-9p c1-9q\">Largement application. Les piquets en fibre de verre soutiennent la croissance des plantes et rendent les plantes plus droites et plus fortes, et il convient aux piquets d&#8217;arbres, aux piquets de p\u00e9pini\u00e8re, aux piquets de fleurs, aux piquets de tomates, aux \u00e9tag\u00e8res pour plantes grimpantes, aux cl\u00f4tures de jardin ou utilis\u00e9s comme piquets marqueurs<\/em><\/li>\n<\/ul>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f1d4eb elementor-widget elementor-widget-image\" data-id=\"2f1d4eb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/elementor\/thumbs\/details-fiberglass-stakes-with-UV-veil-2-qaqhaavu5k9rq66nv2ecm9m5fk73ri1189y2fu1vp4.jpg\" title=\"details-fiberglass-stakes-with-UV-veil-2\" alt=\"details-fiberglass-stakes-with-UV-veil-2\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17a2023 e-con-full e-flex e-con e-parent\" data-id=\"17a2023\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58ecc39 elementor-widget elementor-widget-heading\" data-id=\"58ecc39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Pourquoi choisir des piquets en fibre de verre ?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-628bcae e-flex e-con-boxed e-con e-parent\" data-id=\"628bcae\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69639b4 elementor-widget elementor-widget-html\" data-id=\"69639b4\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<table border=\"2\" cellpadding=\"2\" cellspacing=\"0\" style=\"width:100%;\" class=\"\" align=\"center\" bordercolor=\"#000000\">\n\t<tbody>\n\t\t<tr>\n\t\t\t<td rowspan=\"2\" height=\"172\" class=\"xl68\" width=\"165\" style=\"text-align:center;background-color:#B8D100;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">Des produits<\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl69\" width=\"205\" style=\"text-align:center;background-color:#FF9900;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">Piquets en bambou<\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl69\" width=\"205\" style=\"text-align:center;background-color:#FF9900;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">Piquets en bois<\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl69\" width=\"205\" style=\"text-align:center;background-color:#FF9900;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">Piquet en acier<\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl69\" width=\"205\" style=\"text-align:center;background-color:#FF9900;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">piquet en fibre de verre\n .<\/span><\/strong> \n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td height=\"137\" class=\"xl65\">\n .<img decoding=\"async\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/bamboo.jpg\" width=\"220\" alt=\"\"> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl65\">\n .<img decoding=\"async\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/wooden.jpg\" width=\"220\" alt=\"\"> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl65\">\n .<img decoding=\"async\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/steel.jpg\" width=\"220\" alt=\"\"> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl65\">\n .<img decoding=\"async\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/fiberglass.jpg\" width=\"220\" alt=\"\"> \n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td height=\"34\" class=\"xl68\" style=\"text-align:center;background-color:#B8D100;\">\n\t\t\t\t<strong><span style=\"font-size:12px;\"><span style=\"font-size:14px;\">Stren<\/span><span style=\"font-size:14px;\"><\/span><span style=\"font-size:14px;\">gth<\/span><\/span><span style=\"font-size:12px;\"><\/span><span style=\"font-size:12px;\"><\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4\u26e4\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl67\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;color:#E56600;\"><strong>\u26e4\u26e4\u26e4\u26e4\u26e4<\/strong><\/span> \n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td height=\"34\" class=\"xl68\" style=\"text-align:center;background-color:#B8D100;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">Durabilit\u00e9<\/span><span style=\"font-size:16px;\"><\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl67\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;color:#E56600;\"><strong>\u26e4\u26e4\u26e4\u26e4\u26e4<\/strong><\/span> \n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td height=\"34\" class=\"xl68\" style=\"text-align:center;background-color:#B8D100;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">Weather\n resistanc<\/span><span style=\"font-size:12px;\"><\/span><span style=\"font-size:14px;\">e<\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl67\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;color:#E56600;\"><strong>\u26e4\u26e4\u26e4\u26e4\u26e4<\/strong><\/span> \n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td height=\"34\" class=\"xl68\" style=\"text-align:center;background-color:#B8D100;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">UV resistance<\/span><span style=\"font-size:12px;\"><\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl67\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;color:#E56600;\"><strong>\u26e4\u26e4\u26e4\u26e4\u26e4<\/strong><\/span> \n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td height=\"34\" class=\"xl68\" style=\"text-align:center;background-color:#B8D100;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">Reusa<\/span><\/strong><strong><span style=\"font-size:12px;\"><\/span><\/strong><strong><span style=\"font-size:14px;\">ble<\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl67\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;color:#E56600;\"><strong>\u26e4\u26e4\u26e4\u26e4\u26e4<\/strong><\/span> \n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td height=\"34\" class=\"xl68\" style=\"text-align:center;background-color:#B8D100;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">Eco-friendly<\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl67\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;color:#E56600;\"><strong>\u26e4\u26e4\u26e4\u26e4<\/strong><\/span> \n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td height=\"34\" class=\"xl68\" style=\"text-align:center;background-color:#B8D100;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">Multi purpose<\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl67\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;color:#E56600;\"><strong>\u26e4\u26e4\u26e4\u26e4\u26e4<\/strong><\/span> \n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td height=\"34\" class=\"xl68\" style=\"text-align:center;background-color:#B8D100;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">No rust<\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl67\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;color:#E56600;\"><strong>\u26e4\u26e4\u26e4\u26e4\u26e4<\/strong><\/span> \n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td height=\"34\" class=\"xl68\" style=\"text-align:center;background-color:#B8D100;\">\n\t\t\t\t<strong><span style=\"font-size:14px;\">No fading<\/span><\/strong> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl66\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;\">\u26e4\u26e4\u26e4<\/span> \n\t\t\t<\/td>\n\t\t\t<td class=\"xl67\" style=\"text-align:center;\">\n\t\t\t\t<span style=\"font-size:16px;color:#E56600;\"><strong>\u26e4\u26e4\u26e4\u26e4\u26e4<\/strong><\/span> \n\t\t\t<\/td>\n\t\t<\/tr>\n\t<\/tbody>\n<\/table>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c60d62 e-flex e-con-boxed e-con e-parent\" data-id=\"3c60d62\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b56ad1b elementor-widget elementor-widget-heading\" data-id=\"b56ad1b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Taille<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec2674c elementor-widget elementor-widget-html\" data-id=\"ec2674c\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>\n\t<\/p><table border=\"2\" cellpadding=\"2\" cellspacing=\"0\" style=\"width:100%;\" class=\"\" align=\"center\" bordercolor=\"#000000\">\n\t\t<tbody>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\" style=\"text-align:center;\">\n\t\t\t\t\t<strong>\u00c9paisseur<\/strong>\n\t\t\t\t<\/td>\n\t\t\t\t<td class=\"xl65\" width=\"245\" style=\"text-align:center;\">\n\t\t\t\t\t<strong>Longueur<\/strong>\n\t\t\t\t<\/td>\n\t\t\t\t<td class=\"xl65\" width=\"245\" style=\"text-align:center;\">\n\t\t\t\t\t<strong>Couleur<\/strong>\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 5mm\n\t\t\t\t<\/td>\n\t\t\t\t<td rowspan=\"17\" class=\"xl66\" width=\"245\">\n Toute longueur est la bienvenue\n\t\t\t\t<\/td>\n\t\t\t\t<td rowspan=\"17\" class=\"xl66\" width=\"245\">\n Blanc, vert, bleu, rouge,<br>\nJaune, noir, gris, etc.\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 6mm\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 6.35mm(1\/4\")\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 7mm\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 8mm(5\/16\")\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 9.5mm(3\/8\")\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 10mm\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 11mm\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 12mm\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 12.7mm(1\/2\")\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 14mm\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 15mm\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 16mm(5\/8\")\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 17.5mm(11\/16\")\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 19mm(3\/4\")\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 22mm(7\/8\")\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<td height=\"20\" class=\"xl65\" width=\"245\">\n 25.4mm(1\")\n\t\t\t\t<\/td>\n\t\t\t<\/tr>\n\t\t<\/tbody>\n\t<\/table>\n<span><br>\n<\/span> \n\n<p>\n\t<span><em><span style=\"color:#009900;\"><strong>If you can't find the size you need in the list ,pls let me know. Les produits personnalis\u00e9s sont \u00e9galement les bienvenus !<\/strong><\/span><\/em><\/span> \n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d23ac3f elementor-widget elementor-widget-heading\" data-id=\"d23ac3f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Galerie<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e8b0619 e-flex e-con-boxed e-con e-parent\" data-id=\"5e8b0619\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1ab49a54 e-con-full e-flex e-con e-child\" data-id=\"1ab49a54\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e74612 e-transform elementor-widget elementor-widget-image\" data-id=\"7e74612\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-6.jpg\" class=\"attachment-large size-large wp-image-3669\" alt=\"\" srcset=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-6.jpg 500w, https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-6-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70c43e8b e-con-full e-flex e-con e-child\" data-id=\"70c43e8b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ebb8216 e-transform elementor-widget elementor-widget-image\" data-id=\"1ebb8216\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-7.jpg\" class=\"attachment-large size-large wp-image-3685\" alt=\"\" srcset=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-7.jpg 500w, https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-7-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5956b31 e-con-full e-flex e-con e-child\" data-id=\"5956b31\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5645a50a e-transform elementor-widget elementor-widget-image\" data-id=\"5645a50a\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-8.jpg\" class=\"attachment-large size-large wp-image-3701\" alt=\"\" srcset=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-8.jpg 500w, https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-8-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36b1f578 e-con-full e-flex e-con e-child\" data-id=\"36b1f578\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7cfa07a3 e-transform elementor-widget elementor-widget-image\" data-id=\"7cfa07a3\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-3.jpg\" class=\"attachment-large size-large wp-image-3621\" alt=\"\" srcset=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-3.jpg 500w, https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-3-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1152f38b e-con-full e-flex e-con e-child\" data-id=\"1152f38b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7436d08 e-transform elementor-widget elementor-widget-image\" data-id=\"7436d08\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-4.jpg\" class=\"attachment-large size-large wp-image-3637\" alt=\"\" srcset=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-4.jpg 500w, https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-4-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6783caab e-con-full e-flex e-con e-child\" data-id=\"6783caab\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d1e7a7 e-transform elementor-widget elementor-widget-image\" data-id=\"9d1e7a7\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-5.jpg\" class=\"attachment-large size-large wp-image-3653\" alt=\"\" srcset=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-5.jpg 500w, https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/details-fiberglass-stakes-with-UV-veil-5-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4693a60 e-con-full e-flex e-con e-parent\" data-id=\"4693a60\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:2807,&quot;url&quot;:&quot;https:\\\/\\\/l8e.1d9.myftpupload.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/email-us.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbcd2e9 elementor-widget elementor-widget-heading\" data-id=\"cbcd2e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ENVOYEZ-NOUS UN EMAIL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bc2ff0 elementor-widget elementor-widget-heading\" data-id=\"0bc2ff0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pour toute question, veuillez nous contacter. Nous sommes toujours ouverts pour vous aider et vous offrir nos meilleurs produits.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16165fa elementor-align-center elementor-widget elementor-widget-button\" data-id=\"16165fa\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:sales@ecofiberpultrusion.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ENVOYEZ-NOUS UN EMAIL<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-09fe7b3 e-flex e-con-boxed e-con e-parent\" data-id=\"09fe7b3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DES PRODUITS Piquets en fibre de verre recouverts d&#8217;un voile polyester anti-UV Piquets en fibre de verre recouverts d&#8217;un voile polyester anti-UV Le voile de polyester peut prot\u00e9ger la fibre et la r\u00e9sine \u00e0 l&#8217;int\u00e9rieur des piquets des rayons ultraviolets directs, de sorte que le produit a une dur\u00e9e de vie plus longue. Le voile [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3349,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Piquets en fibre de verre avec voile UV - EcoFiber Pultrusion Products<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piquets en fibre de verre avec voile UV - EcoFiber Pultrusion Products\" \/>\n<meta property=\"og:description\" content=\"DES PRODUITS Piquets en fibre de verre recouverts d&#8217;un voile polyester anti-UV Piquets en fibre de verre recouverts d&#8217;un voile polyester anti-UV Le voile de polyester peut prot\u00e9ger la fibre et la r\u00e9sine \u00e0 l&#8217;int\u00e9rieur des piquets des rayons ultraviolets directs, de sorte que le produit a une dur\u00e9e de vie plus longue. Le voile [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/\" \/>\n<meta property=\"og:site_name\" content=\"EcoFiber Pultrusion Products\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-14T06:18:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/elementor\/thumbs\/details-fiberglass-stakes-with-UV-veil-qaqgyv6j04m6gyson4fra5i98skc42mlno7e0dbim8.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/\",\"url\":\"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/\",\"name\":\"Piquets en fibre de verre avec voile UV - EcoFiber Pultrusion Products\",\"isPartOf\":{\"@id\":\"https:\/\/ecofiberpultrusion.com\/#website\"},\"datePublished\":\"2023-07-31T09:13:24+00:00\",\"dateModified\":\"2023-09-14T06:18:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ecofiberpultrusion.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des produits\",\"item\":\"https:\/\/ecofiberpultrusion.com\/products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Piquets en fibre de verre avec voile UV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ecofiberpultrusion.com\/#website\",\"url\":\"https:\/\/ecofiberpultrusion.com\/\",\"name\":\"EcoFiber Pultrusion Products\",\"description\":\"A professional fiberglass and carbon fiber products manufacturer\",\"publisher\":{\"@id\":\"https:\/\/ecofiberpultrusion.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ecofiberpultrusion.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ecofiberpultrusion.com\/#organization\",\"name\":\"EcoFiber Pultrusion Products\",\"url\":\"https:\/\/ecofiberpultrusion.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/ecofiberpultrusion.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/cropped-logo-middle.png\",\"contentUrl\":\"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/cropped-logo-middle.png\",\"width\":373,\"height\":115,\"caption\":\"EcoFiber Pultrusion Products\"},\"image\":{\"@id\":\"https:\/\/ecofiberpultrusion.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piquets en fibre de verre avec voile UV - EcoFiber Pultrusion Products","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/","og_locale":"fr_FR","og_type":"article","og_title":"Piquets en fibre de verre avec voile UV - EcoFiber Pultrusion Products","og_description":"DES PRODUITS Piquets en fibre de verre recouverts d&#8217;un voile polyester anti-UV Piquets en fibre de verre recouverts d&#8217;un voile polyester anti-UV Le voile de polyester peut prot\u00e9ger la fibre et la r\u00e9sine \u00e0 l&#8217;int\u00e9rieur des piquets des rayons ultraviolets directs, de sorte que le produit a une dur\u00e9e de vie plus longue. Le voile [&hellip;]","og_url":"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/","og_site_name":"EcoFiber Pultrusion Products","article_modified_time":"2023-09-14T06:18:59+00:00","og_image":[{"url":"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/elementor\/thumbs\/details-fiberglass-stakes-with-UV-veil-qaqgyv6j04m6gyson4fra5i98skc42mlno7e0dbim8.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/","url":"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/","name":"Piquets en fibre de verre avec voile UV - EcoFiber Pultrusion Products","isPartOf":{"@id":"https:\/\/ecofiberpultrusion.com\/#website"},"datePublished":"2023-07-31T09:13:24+00:00","dateModified":"2023-09-14T06:18:59+00:00","breadcrumb":{"@id":"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ecofiberpultrusion.com\/products\/fiberglass-stakes-with-uv-veil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecofiberpultrusion.com\/"},{"@type":"ListItem","position":2,"name":"Des produits","item":"https:\/\/ecofiberpultrusion.com\/products\/"},{"@type":"ListItem","position":3,"name":"Piquets en fibre de verre avec voile UV"}]},{"@type":"WebSite","@id":"https:\/\/ecofiberpultrusion.com\/#website","url":"https:\/\/ecofiberpultrusion.com\/","name":"EcoFiber Pultrusion Products","description":"A professional fiberglass and carbon fiber products manufacturer","publisher":{"@id":"https:\/\/ecofiberpultrusion.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecofiberpultrusion.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ecofiberpultrusion.com\/#organization","name":"EcoFiber Pultrusion Products","url":"https:\/\/ecofiberpultrusion.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ecofiberpultrusion.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/cropped-logo-middle.png","contentUrl":"https:\/\/ecofiberpultrusion.com\/wp-content\/uploads\/2023\/08\/cropped-logo-middle.png","width":373,"height":115,"caption":"EcoFiber Pultrusion Products"},"image":{"@id":"https:\/\/ecofiberpultrusion.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ecofiberpultrusion.com\/fr\/wp-json\/wp\/v2\/pages\/5742"}],"collection":[{"href":"https:\/\/ecofiberpultrusion.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecofiberpultrusion.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecofiberpultrusion.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecofiberpultrusion.com\/fr\/wp-json\/wp\/v2\/comments?post=5742"}],"version-history":[{"count":7,"href":"https:\/\/ecofiberpultrusion.com\/fr\/wp-json\/wp\/v2\/pages\/5742\/revisions"}],"predecessor-version":[{"id":7198,"href":"https:\/\/ecofiberpultrusion.com\/fr\/wp-json\/wp\/v2\/pages\/5742\/revisions\/7198"}],"up":[{"embeddable":true,"href":"https:\/\/ecofiberpultrusion.com\/fr\/wp-json\/wp\/v2\/pages\/3349"}],"wp:attachment":[{"href":"https:\/\/ecofiberpultrusion.com\/fr\/wp-json\/wp\/v2\/media?parent=5742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}